{"id":46,"count":9,"description":"","link":"https:\/\/carlossousa.pt\/en\/product-category\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/","name":"Flat Webbing Slings","slug":"cintas-de-elevacao-com-alcas","taxonomy":"product_cat","parent":20,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carlossousa.pt\/en\/product-category\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carlossousa.pt\/en\/product-category\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlos Sousa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/categoria-produto\\\/cintas-de-elevacao\\\/cintas-de-elevacao-com-alcas\\\/\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/categoria-produto\\\/cintas-de-elevacao\\\/cintas-de-elevacao-com-alcas\\\/\",\"name\":\"Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/categoria-produto\\\/cintas-de-elevacao\\\/cintas-de-elevacao-com-alcas\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/categoria-produto\\\/cintas-de-elevacao\\\/cintas-de-elevacao-com-alcas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/carlossousa.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cintas de Eleva\u00e7\u00e3o\",\"item\":\"https:\\\/\\\/carlossousa.pt\\\/categoria-produto\\\/cintas-de-elevacao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cintas de Eleva\u00e7\u00e3o com Al\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#website\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/\",\"name\":\"Carlos Sousa\",\"description\":\"Fabrico de Cintas de Eleva\u00e7\u00e3o e Amarra\u00e7\u00e3o, Fitas Tecidas, Acess\u00f3rios, Slings e Bigbags.\",\"publisher\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/carlossousa.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#organization\",\"name\":\"Carlos Sousa\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Asset-1.png\",\"contentUrl\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Asset-1.png\",\"width\":1771,\"height\":558,\"caption\":\"Carlos Sousa\"},\"image\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carlossousa.pt\/en\/product-category\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/","og_locale":"en_GB","og_type":"article","og_title":"Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa","og_url":"https:\/\/carlossousa.pt\/en\/product-category\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/","og_site_name":"Carlos Sousa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/carlossousa.pt\/categoria-produto\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/","url":"https:\/\/carlossousa.pt\/categoria-produto\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/","name":"Arquivo de Cintas de Eleva\u00e7\u00e3o com Al\u00e7as - Carlos Sousa","isPartOf":{"@id":"https:\/\/carlossousa.pt\/#website"},"breadcrumb":{"@id":"https:\/\/carlossousa.pt\/categoria-produto\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/carlossousa.pt\/categoria-produto\/cintas-de-elevacao\/cintas-de-elevacao-com-alcas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/carlossousa.pt\/"},{"@type":"ListItem","position":2,"name":"Cintas de Eleva\u00e7\u00e3o","item":"https:\/\/carlossousa.pt\/categoria-produto\/cintas-de-elevacao\/"},{"@type":"ListItem","position":3,"name":"Cintas de Eleva\u00e7\u00e3o com Al\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/carlossousa.pt\/#website","url":"https:\/\/carlossousa.pt\/","name":"Carlos Sousa","description":"Fabrico de Cintas de Eleva\u00e7\u00e3o e Amarra\u00e7\u00e3o, Fitas Tecidas, Acess\u00f3rios, Slings e Bigbags.","publisher":{"@id":"https:\/\/carlossousa.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carlossousa.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/carlossousa.pt\/#organization","name":"Carlos Sousa","url":"https:\/\/carlossousa.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/carlossousa.pt\/#\/schema\/logo\/image\/","url":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/05\/Asset-1.png","contentUrl":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/05\/Asset-1.png","width":1771,"height":558,"caption":"Carlos Sousa"},"image":{"@id":"https:\/\/carlossousa.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_cat\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_cat\/20"}],"wp:post_type":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product?product_cat=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}