{"id":961,"date":"2022-06-27T10:25:46","date_gmt":"2022-06-27T10:25:46","guid":{"rendered":"https:\/\/carlossousa.pt\/?post_type=product&#038;p=961"},"modified":"2022-07-15T10:48:31","modified_gmt":"2022-07-15T10:48:31","slug":"tensor-completo-com-gancho-em-j-75mm","status":"publish","type":"product","link":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/","title":{"rendered":"Complete Ratchet with J-hook 75mm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>SHF 50 daN_ STF 500 daN<\/p>\n<p>LC5000 daN<\/p>","protected":false},"featured_media":962,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[49,55],"product_tag":[],"class_list":{"0":"post-961","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cintas-de-amarracao","7":"product_cat-tensor-completo","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tensor completo com gancho em J 75mm - Carlos Sousa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tensor completo com gancho em J 75mm - Carlos Sousa\" \/>\n<meta property=\"og:description\" content=\"SHF 50 daN_ STF 500 daN  LC5000 daN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlos Sousa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T10:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/06\/KR_04215-copy-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/\",\"name\":\"Tensor completo com gancho em J 75mm - Carlos Sousa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/KR_04215-copy-scaled.jpg\",\"datePublished\":\"2022-06-27T10:25:46+00:00\",\"dateModified\":\"2022-07-15T10:48:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/KR_04215-copy-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/KR_04215-copy-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Tensor completo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/en\\\/product\\\/tensor-completo-com-gancho-em-j-75mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/carlossousa.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/carlossousa.pt\\\/cintas-de-amarracao-cintas-de-elevacao-fitas-slings\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tensor completo com gancho em J 75mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#website\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/\",\"name\":\"Carlos Sousa\",\"description\":\"Fabrico de Cintas de Eleva\u00e7\u00e3o e Amarra\u00e7\u00e3o, Fitas Tecidas, Acess\u00f3rios, Slings e Bigbags.\",\"publisher\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/carlossousa.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#organization\",\"name\":\"Carlos Sousa\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Asset-1.png\",\"contentUrl\":\"https:\\\/\\\/carlossousa.pt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Asset-1.png\",\"width\":1771,\"height\":558,\"caption\":\"Carlos Sousa\"},\"image\":{\"@id\":\"https:\\\/\\\/carlossousa.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tensor completo com gancho em J 75mm - Carlos Sousa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/","og_locale":"en_GB","og_type":"article","og_title":"Tensor completo com gancho em J 75mm - Carlos Sousa","og_description":"SHF 50 daN_ STF 500 daN  LC5000 daN","og_url":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/","og_site_name":"Carlos Sousa","article_modified_time":"2022-07-15T10:48:31+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/06\/KR_04215-copy-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/","url":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/","name":"Tensor completo com gancho em J 75mm - Carlos Sousa","isPartOf":{"@id":"https:\/\/carlossousa.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/#primaryimage"},"image":{"@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/#primaryimage"},"thumbnailUrl":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/06\/KR_04215-copy-scaled.jpg","datePublished":"2022-06-27T10:25:46+00:00","dateModified":"2022-07-15T10:48:31+00:00","breadcrumb":{"@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/#primaryimage","url":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/06\/KR_04215-copy-scaled.jpg","contentUrl":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/06\/KR_04215-copy-scaled.jpg","width":2560,"height":1707,"caption":"Tensor completo"},{"@type":"BreadcrumbList","@id":"https:\/\/carlossousa.pt\/en\/product\/tensor-completo-com-gancho-em-j-75mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/carlossousa.pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/carlossousa.pt\/cintas-de-amarracao-cintas-de-elevacao-fitas-slings\/"},{"@type":"ListItem","position":3,"name":"Tensor completo com gancho em J 75mm"}]},{"@type":"WebSite","@id":"https:\/\/carlossousa.pt\/#website","url":"https:\/\/carlossousa.pt\/","name":"Carlos Sousa","description":"Fabrico de Cintas de Eleva\u00e7\u00e3o e Amarra\u00e7\u00e3o, Fitas Tecidas, Acess\u00f3rios, Slings e Bigbags.","publisher":{"@id":"https:\/\/carlossousa.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carlossousa.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/carlossousa.pt\/#organization","name":"Carlos Sousa","url":"https:\/\/carlossousa.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/carlossousa.pt\/#\/schema\/logo\/image\/","url":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/05\/Asset-1.png","contentUrl":"https:\/\/carlossousa.pt\/wp-content\/uploads\/2022\/05\/Asset-1.png","width":1771,"height":558,"caption":"Carlos Sousa"},"image":{"@id":"https:\/\/carlossousa.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/comments?post=961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/media\/962"}],"wp:attachment":[{"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_brand?post=961"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_cat?post=961"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/carlossousa.pt\/en\/wp-json\/wp\/v2\/product_tag?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}